{"id":10961,"date":"2026-05-27T08:52:08","date_gmt":"2026-05-27T06:52:08","guid":{"rendered":"https:\/\/www.naturemweltasbl.lu\/?p=10961"},"modified":"2026-05-28T10:45:51","modified_gmt":"2026-05-28T08:45:51","slug":"bericht-generalversammlung-2026","status":"publish","type":"post","link":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/","title":{"rendered":"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&#038;\u00ebmwelt a.s.b.l. vom 18. April 2026"},"content":{"rendered":"<p>Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.<\/p>\n<p>Nach der Verabschiedung der neuen Satzung im Jahr 2025 wurde f\u00fcr die Generalversammlung 2026 eine Neuerung eingef\u00fchrt: Die Anzahl der Vollmachten pro anwesendem Mitglied war auf eine begrenzt. 74 anwesende oder vertretene delegierte Mitglieder aus 18 Mitgliedsverb\u00e4nden (Ortsverb\u00e4nden) und 5 Partnerverb\u00e4nden nahmen daran teil. 34 Mitglieder ohne Stimmrecht waren anwesend. Als Ehreng\u00e4ste waren Nora Elvinger, Vertreterin des Ministeriums f\u00fcr Umwelt, Klima und Biodiversit\u00e4t, und Mike Molling, stellvertretender Direktor der Natur- und Forstverwaltung, anwesend.<\/p>\n<p>Zum ersten Mal in der Geschichte von natur&amp;\u00ebmwelt waren nicht nur die delegierten Mitglieder zur Generalversammlung eingeladen, sondern alle Mitglieder von natur&amp;\u00ebmwelt. Mit gro\u00dfer Freude stellte der Vorstand einen gut gef\u00fcllten Saal und zahlreiche interessierte Besucher fest.<\/p>\n<p>Emil Mentgen, Vorsitzender der Ortsgruppe \u201eSektioun Kanton Gr\u00e9iwemaacher\u201c, er\u00f6ffnete die Generalversammlung, indem er die Mitglieder begr\u00fc\u00dfte und einen kurzen R\u00fcckblick auf das 40-j\u00e4hrige Jubil\u00e4um der Ortsgruppe gab, die seit 1985 besteht. Anschlie\u00dfend richtete der erste Beigeordnete der Gemeinde Grevenmacher, Marc Krier, einige Begr\u00fc\u00dfungsworte an das Publikum, bevor der Vorsitzende Roby Biwer auf das vergangene Jahr zur\u00fcckblickte. Zudem dankte er dem Mitarbeiterteam von natur&amp;\u00ebmwelt und den ehrenamtlichen Helfern der Sektion Kanton Gr\u00e9iwemaacher f\u00fcr die Organisation der Generalversammlung.<\/p>\n<p>Anschlie\u00dfend stellte die Generalsekret\u00e4rin Joy Mentgen den j\u00e4hrlichen Verwaltungsbericht f\u00fcr 2025 vor. Sie ging auf die Zahlen der Aktivit\u00e4ten und Projekte ein, die natur&amp;\u00ebmwelt asbl im Laufe des vergangenen Jahres durchgef\u00fchrt hatte, und wies darauf hin, dass dieser \u00dcberblick nur einen kleinen Teil aller Aktivit\u00e4ten darstelle, von denen hier einige genannt seien:<\/p>\n<p>Im Jahr 2025 stieg die Zahl der Anfragen bei der Naturberatungsstelle von natur&amp;\u00ebmwelt erneut um 25 % (2400 Anfragen gegen\u00fcber 1900 Anfragen im Jahr 2024). Eines der Hauptthemen war die Gelbfu\u00df-Hornisse (Vespa velutina), eine invasive Art, die sich in Luxemburg zunehmend ausbreitet. Im Rahmen des Projekts \u201eBest\u00ebbser \u2013 M\u00e9i w\u00e9i Beien\u201c entwickelten die Teams f\u00fcr Kommunikation, Naturberatung und Sensibilisierung gemeinsam ein \u201ePixi\u201c-Buch \u00fcber Wespen und ein dazugeh\u00f6riges p\u00e4dagogisches Begleitheft. In diesem Zusammenhang wurden Schulungen zum Bau und zur Aufstellung von Insektenhotels f\u00fcr die Mitarbeiter des technischen Dienstes der Gemeinden angeboten. Im Bereich der Ornithologie f\u00fchrte das Personal der Zentrale f\u00fcr Vogelkunde zahlreiche Monitoring-Ma\u00dfnahmen durch, wie zum Beispiel die Beobachtung von Spechten oder des Grauschn\u00e4ppers. Wie in den Vorjahren wurden in unseren drei Beringungsstationen von den Beringern und zahlreichen Freiwilligen eine betr\u00e4chtliche Anzahl von V\u00f6geln beringt (insgesamt 38.300 V\u00f6gel, 7.500 Individuen mehr als im Jahr 2024). Im Bereich der ehrenamtlichen Arbeit unterst\u00fctzte die neue Sektionskoordinatorin, Jil Baustert, die Sektionen bei der Organisation und Durchf\u00fchrung ihrer Aktivit\u00e4ten, darunter die \u201eChantiers Nature\u201c oder F\u00fchrungen. Das Team f\u00fcr \u00d6ffentlichkeitsarbeit setzte seine Arbeit zur Vermittlung von Natur- und Nachhaltigkeitsbildung fort, mit Aktivit\u00e4ten f\u00fcr Schulklassen und Kinder- und Jugendheime, aber auch f\u00fcr Familien sowie f\u00fcr die Mitglieder des Regulus Junior Clubs und der Regulus Jugendgruppe. So waren die verschiedenen \u201e\u00d6ko-Camps\u201c w\u00e4hrend der Schulferien erneut ein gro\u00dfer Erfolg.<\/p>\n<p>Einzelheiten zu den Aktivit\u00e4ten finden Sie im Jahresbericht (Regulus 2026\/1) und auf der Website (www.naturemwelt.lu).<\/p>\n<p>Der von unserem Schatzmeister Benji Kontz vorgelegte Finanzbericht wies ein negatives Ergebnis (-147.711,90 \u20ac) aus, das zwar immer noch betr\u00e4chtlich ist, aber deutlich geringer ausf\u00e4llt als im Vorjahr (-273.390 \u20ac im Jahr 2024). Der Haushalt f\u00fcr 2026 sieht einen Verlust von 47.330 \u20ac vor. Das Ziel des Teams von natur&amp;\u00ebmwelt asbl und des Verwaltungsrats bleibt nat\u00fcrlich, im folgenden Jahr wieder einen ausgeglichenen Haushalt zu erreichen, und es wird sich auch 2026 weiterhin f\u00fcr dieses Ziel einsetzen.<\/p>\n<p>Im Namen der Kassenpr\u00fcferinnen und Kassenpr\u00fcfer erteilte Malou Grasges den Verwaltungsratsmitgliedern Entlastung f\u00fcr das Jahr 2025, was von der Versammlung einstimmig best\u00e4tigt wurde. In diesem Zusammenhang dankte der Verwaltungsrat den Kassenpr\u00fcferinnen und Kassenpr\u00fcfern sowie Marie-Anne Pissinger f\u00fcr ihre langj\u00e4hrige ehrenamtliche Arbeit.<\/p>\n<p>Carlos de Jesus gab seinen R\u00fccktritt als Kassenpr\u00fcfer bekannt und wurde durch Marie-Anne Pissinger ersetzt. Die Kassenpr\u00fcferinnen Annette Kemp-Klemann und Malou wurden f\u00fcr das kommende Jahr wiedergew\u00e4hlt.<\/p>\n<p>Dem Verwaltungsrat wurde einstimmig Entlastung f\u00fcr seine Gesch\u00e4ftsf\u00fchrung erteilt. Nach der Verabschiedung der neuen Satzung im Jahr 2025 schied kein Mitglied des Verwaltungsrats aus. Marie-Anne Pissinger gab jedoch ihren R\u00fccktritt aus dem Verwaltungsrat bekannt. Lynn Kraus, die sich f\u00fcr einen Sitz im Verwaltungsrat beworben hatte, wurde einstimmig gew\u00e4hlt. Damit z\u00e4hlt der Verwaltungsrat derzeit 13 Mitglieder.<\/p>\n<p>Jean-Weiss gab seinen R\u00fccktritt vom Amt des Vizepr\u00e4sidenten bekannt. Max Steinmetz wird ihn ersetzen.<\/p>\n<p>Vierzehn neue Delegierte wurden gew\u00e4hlt: Philippe Schmitz, Philippe Lutty, Alice Heinen, Hubert Braquet, Lisa Pez, Tiago Pinto, Martine Fisch, Lynn Kraus, Nicole Kleer-Dasbourg, Brigitte Konsbruck-Barthelmy, Raymond Schannes-Hiery, Christine Andr\u00e9, Nico Muller, Keven Muller.<\/p>\n<p>Dreizehn Delegierte schieden aus: Gilles Pansin, Catherine Gonner, Marcel Barbier, B\u00e9atrice Chagnon, Gilles Martini, Joe Kremer Robert, Lynn Duchamp, Hannes Heister, Rudy Braun, Romain Gaspar, Gaston Fohl, Benji Kontz, Lucie Bonora. Ihnen wurde f\u00fcr ihr ehrenamtliches Engagement in den letzten Jahren gedankt.<\/p>\n<p>Wie in der Satzung vorgesehen, haben die delegierten Mitglieder, die zum dritten Mal in Folge nicht anwesend, nicht entschuldigt oder nicht vertreten waren, ihr Stimmrecht verloren.<\/p>\n<p>Der Vorstand schlug der Generalversammlung vor, bestimmte inaktive Ortsgruppen aufzul\u00f6sen. Dabei handelt es sich um die Ortsgruppen D\u00e9ifferdeng, P\u00e9iteng, Esch-Uelzecht, Jongl\u00ebnster, Keespelt-Meespelt und Wolz. Die Generalversammlung stimmte f\u00fcr die offizielle Aufl\u00f6sung dieser Ortsverb\u00e4nde. Die Mitglieder werden in aktive Ortsverb\u00e4nde \u00fcbernommen.<\/p>\n<p>Dar\u00fcber hinaus stellte der Vorstand die Pl\u00e4ne des Ortsverbandes Gemeng Suessem vor, der vorschlug, die Mitglieder der Ortsverb\u00e4nde D\u00e9ifferd\u00e9ng und P\u00e9iteng aufzunehmen und seinen Namen in Ortsverband Kordall zu \u00e4ndern.<\/p>\n<p>Anschlie\u00dfend informierte der Vorstand \u00fcber einige aktuelle Themen, darunter das Dossier \u201eStrategie 2030\/2035\u201c. Die Generalsekret\u00e4rin Joy Mentgen stellte kurz den Entwicklungsprozess der Strategie in den letzten Monaten vor. So kamen der Vorstand, die Gesch\u00e4ftsleitung und die Mitarbeiter in verschiedenen Konstellationen zusammen, um eine klare Strategie f\u00fcr das kommende Jahrzehnt auszuarbeiten. In diesem Zusammenhang sind alle bei natur&amp;\u00ebmwelt aktiven Freiwilligen eingeladen, ihre Meinung zu \u00e4u\u00dfern, und zwar im Rahmen eines Workshops, der am Montag, dem 28. September 2026, im SNJ-Zentrum in Hollenfels stattfindet. Die Einladung finden Sie im Veranstaltungskalender auf der Website (www.naturemwelt.lu) sowie in der gedruckten Ausgabe des Regulus.<\/p>\n<p>Anschlie\u00dfend wurden zwei aktuelle Projekte von natur&amp;\u00ebmwelt vorgestellt: das Projekt \u201eurban birds\u201c, erl\u00e4utert von Catherine Kirsch und Rick Juncker von der Centrale Ornithologique, sowie das Projekt \u201enaturreseau\u201c, pr\u00e4sentiert von Simon Biver. Dies bot den anwesenden Mitgliedern eine gute Gelegenheit, diese neuen Projekte kennenzulernen und den Expert*innen Fragen zu stellen.<\/p>\n<p>Anschlie\u00dfend gaben die beiden anderen Einrichtungen von natur&amp;\u00ebmwelt einen \u00dcberblick \u00fcber ihre Aktivit\u00e4ten im Jahr 2025. Der Bericht der Stiftung natur&amp;\u00ebmwelt H\u00ebllef fir d&#8217;Natur wurde von Direktor Frankie Thielen vorgestellt, der Bericht der Fleegestatioun fir w\u00ebll D\u00e9ieren vom neuen Direktor Georg Xander.<\/p>\n<p>Abschlie\u00dfend lobte Nora Elvinger vom Umweltministerium natur&amp;\u00ebmwelt asbl f\u00fcr ihr jahrzehntelanges Engagement f\u00fcr den Natur- und Umweltschutz. Sie betonte, dass natur&amp;\u00ebmwelt der wichtigste Partner im privaten Sektor sei, um die Ziele des Ministeriums im Bereich des Naturschutzes zu erreichen. Sie versprach, dass das Ministerium den Verein weiterhin unterst\u00fctzen werde, damit dieser alle seine Projekte, die sie als von sehr hoher Qualit\u00e4t bezeichnete, weiterf\u00fchren k\u00f6nne.<\/p>\n<p>Vor dem Ende der Versammlung wurden mehrere Personen f\u00fcr ihr Engagement geehrt. Der Gesch\u00e4ftsf\u00fchrerin von natur&amp;\u00ebmwelt, Claudine Felten, wurde f\u00fcr ihre 25-j\u00e4hrige T\u00e4tigkeit bei der Stiftung \u201eH\u00ebllef fir d\u2019Natur\u201c und bei natur&amp;\u00ebmwelt a.s.b.l. gedankt. Die goldene Auszeichnung \u201eG\u00eblle Sp\u00e9ngel\u201c wurde an John Schmit und Marc Theis (Sektion Kanton Gr\u00e9iwemaacher) sowie an Jos Frosio (Sektion Beetebuerg-Monnerech-R\u00e9iserbann) f\u00fcr ihr langj\u00e4hriges Engagement bei natur&amp;\u00ebmwelt verliehen.<\/p>\n<p>Im Anschluss an die Generalversammlung fand ein geselliges \u201eWalking Lunch\u201c statt, das von natur&amp;\u00ebmwelt asbl angeboten wurde.<\/p>\n<p>Ein gro\u00dfes Dankesch\u00f6n an die ehrenamtlichen Helfer der Ortsgruppe natur&amp;\u00ebmwelt Kanton Gr\u00e9iwemaacher f\u00fcr die Vorbereitung dieser sehr gelungenen Generalversammlung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, [&#8230;]<\/p>\n","protected":false},"author":11,"featured_media":10538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[196],"tags":[],"post_folder":[],"class_list":["post-10961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&amp;\u00ebmwelt a.s.b.l. vom 18. April 2026 - natur&amp;\u00ebmwelt a.s.b.l.<\/title>\n<meta name=\"description\" content=\"Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&amp;\u00ebmwelt a.s.b.l. vom 18. April 2026 - natur&amp;\u00ebmwelt a.s.b.l.\" \/>\n<meta property=\"og:description\" content=\"Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"natur&amp;\u00ebmwelt a.s.b.l.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naturemwelt\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T06:52:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T08:45:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2026\/04\/5-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charly Beck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Natur_an_Emwelt\" \/>\n<meta name=\"twitter:site\" content=\"@Natur_an_Emwelt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charly Beck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/\"},\"author\":{\"name\":\"Charly Beck\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#\\\/schema\\\/person\\\/c3e7c4b432b6869ef4e550e2ae779a9f\"},\"headline\":\"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&#038;\u00ebmwelt a.s.b.l. vom 18. April 2026\",\"datePublished\":\"2026-05-27T06:52:08+00:00\",\"dateModified\":\"2026-05-28T08:45:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/\"},\"wordCount\":1389,\"publisher\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/\",\"url\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/\",\"name\":\"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&\u00ebmwelt a.s.b.l. vom 18. April 2026 - natur&amp;\u00ebmwelt a.s.b.l.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5.jpg\",\"datePublished\":\"2026-05-27T06:52:08+00:00\",\"dateModified\":\"2026-05-28T08:45:51+00:00\",\"description\":\"Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/bericht-generalversammlung-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&#038;\u00ebmwelt a.s.b.l. vom 18. April 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#website\",\"url\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/\",\"name\":\"natur&\u00ebmwelt a.s.b.l.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#organization\",\"name\":\"natur&\u00ebmwelt a.s.b.l.\",\"url\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/NE_Logo_asbl_RGB-e1720014142276.png\",\"contentUrl\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/NE_Logo_asbl_RGB-e1720014142276.png\",\"width\":432,\"height\":254,\"caption\":\"natur&\u00ebmwelt a.s.b.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/naturemwelt\\\/\",\"https:\\\/\\\/x.com\\\/Natur_an_Emwelt\",\"https:\\\/\\\/www.instagram.com\\\/naturemwelt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/naturemwelt\",\"https:\\\/\\\/lu.linkedin.com\\\/company\\\/naturemweltasbl?trk=similar-pages\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/#\\\/schema\\\/person\\\/c3e7c4b432b6869ef4e550e2ae779a9f\",\"name\":\"Charly Beck\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7334dbd59fdcb120187a28dd92e90d67cde56f90ed153d7372091b08457506d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7334dbd59fdcb120187a28dd92e90d67cde56f90ed153d7372091b08457506d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7334dbd59fdcb120187a28dd92e90d67cde56f90ed153d7372091b08457506d3?s=96&d=mm&r=g\",\"caption\":\"Charly Beck\"},\"sameAs\":[\"https:\\\/\\\/naturemweltasbl.lu\"],\"url\":\"https:\\\/\\\/www.naturemweltasbl.lu\\\/de\\\/author\\\/charly-n-e\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&\u00ebmwelt a.s.b.l. vom 18. April 2026 - natur&amp;\u00ebmwelt a.s.b.l.","description":"Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/","og_locale":"de_DE","og_type":"article","og_title":"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&\u00ebmwelt a.s.b.l. vom 18. April 2026 - natur&amp;\u00ebmwelt a.s.b.l.","og_description":"Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.","og_url":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/","og_site_name":"natur&amp;\u00ebmwelt a.s.b.l.","article_publisher":"https:\/\/www.facebook.com\/naturemwelt\/","article_published_time":"2026-05-27T06:52:08+00:00","article_modified_time":"2026-05-28T08:45:51+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2026\/04\/5-1024x683.jpg","type":"image\/jpeg"}],"author":"Charly Beck","twitter_card":"summary_large_image","twitter_creator":"@Natur_an_Emwelt","twitter_site":"@Natur_an_Emwelt","twitter_misc":{"Verfasst von":"Charly Beck","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#article","isPartOf":{"@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/"},"author":{"name":"Charly Beck","@id":"https:\/\/www.naturemweltasbl.lu\/#\/schema\/person\/c3e7c4b432b6869ef4e550e2ae779a9f"},"headline":"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&#038;\u00ebmwelt a.s.b.l. vom 18. April 2026","datePublished":"2026-05-27T06:52:08+00:00","dateModified":"2026-05-28T08:45:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/"},"wordCount":1389,"publisher":{"@id":"https:\/\/www.naturemweltasbl.lu\/#organization"},"image":{"@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2026\/04\/5.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/","url":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/","name":"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&\u00ebmwelt a.s.b.l. vom 18. April 2026 - natur&amp;\u00ebmwelt a.s.b.l.","isPartOf":{"@id":"https:\/\/www.naturemweltasbl.lu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2026\/04\/5.jpg","datePublished":"2026-05-27T06:52:08+00:00","dateModified":"2026-05-28T08:45:51+00:00","description":"Die satzungsm\u00e4\u00dfige Generalversammlung fand am Samstag, dem 18. April 2026, im Kulturzentrum Machera in Grevenmacher statt.","breadcrumb":{"@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#primaryimage","url":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2026\/04\/5.jpg","contentUrl":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2026\/04\/5.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.naturemweltasbl.lu\/de\/bericht-generalversammlung-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.naturemweltasbl.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Bericht \u00fcber die satzungsm\u00e4\u00dfige Generalversammlung von natur&#038;\u00ebmwelt a.s.b.l. vom 18. April 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.naturemweltasbl.lu\/#website","url":"https:\/\/www.naturemweltasbl.lu\/","name":"natur&\u00ebmwelt a.s.b.l.","description":"","publisher":{"@id":"https:\/\/www.naturemweltasbl.lu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naturemweltasbl.lu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.naturemweltasbl.lu\/#organization","name":"natur&\u00ebmwelt a.s.b.l.","url":"https:\/\/www.naturemweltasbl.lu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.naturemweltasbl.lu\/#\/schema\/logo\/image\/","url":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2024\/07\/NE_Logo_asbl_RGB-e1720014142276.png","contentUrl":"https:\/\/www.naturemweltasbl.lu\/wp-content\/uploads\/2024\/07\/NE_Logo_asbl_RGB-e1720014142276.png","width":432,"height":254,"caption":"natur&\u00ebmwelt a.s.b.l."},"image":{"@id":"https:\/\/www.naturemweltasbl.lu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naturemwelt\/","https:\/\/x.com\/Natur_an_Emwelt","https:\/\/www.instagram.com\/naturemwelt\/","https:\/\/www.youtube.com\/user\/naturemwelt","https:\/\/lu.linkedin.com\/company\/naturemweltasbl?trk=similar-pages"]},{"@type":"Person","@id":"https:\/\/www.naturemweltasbl.lu\/#\/schema\/person\/c3e7c4b432b6869ef4e550e2ae779a9f","name":"Charly Beck","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7334dbd59fdcb120187a28dd92e90d67cde56f90ed153d7372091b08457506d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7334dbd59fdcb120187a28dd92e90d67cde56f90ed153d7372091b08457506d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7334dbd59fdcb120187a28dd92e90d67cde56f90ed153d7372091b08457506d3?s=96&d=mm&r=g","caption":"Charly Beck"},"sameAs":["https:\/\/naturemweltasbl.lu"],"url":"https:\/\/www.naturemweltasbl.lu\/de\/author\/charly-n-e\/"}]}},"_links":{"self":[{"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/posts\/10961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/comments?post=10961"}],"version-history":[{"count":2,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/posts\/10961\/revisions"}],"predecessor-version":[{"id":10970,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/posts\/10961\/revisions\/10970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/media\/10538"}],"wp:attachment":[{"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/media?parent=10961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/categories?post=10961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/tags?post=10961"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.naturemweltasbl.lu\/de\/wp-json\/wp\/v2\/post_folder?post=10961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}